{"id":47,"count":1,"description":"","link":"https:\/\/jeroenterlingen.nl\/site\/tag\/uitgeverij-de-kring\/","name":"Uitgeverij De Kring","slug":"uitgeverij-de-kring","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Uitgeverij De Kring Archieven - Jeroen Terlingen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jeroenterlingen.nl\/site\/tag\/uitgeverij-de-kring\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Uitgeverij De Kring Archieven - Jeroen Terlingen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jeroenterlingen.nl\/site\/tag\/uitgeverij-de-kring\/\" \/>\n<meta property=\"og:site_name\" content=\"Jeroen Terlingen\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/jeroenterlingen.nl\\\/site\\\/tag\\\/uitgeverij-de-kring\\\/\",\"url\":\"https:\\\/\\\/jeroenterlingen.nl\\\/site\\\/tag\\\/uitgeverij-de-kring\\\/\",\"name\":\"Uitgeverij De Kring Archieven - Jeroen Terlingen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jeroenterlingen.nl\\\/site\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jeroenterlingen.nl\\\/site\\\/tag\\\/uitgeverij-de-kring\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jeroenterlingen.nl\\\/site\\\/tag\\\/uitgeverij-de-kring\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/jeroenterlingen.nl\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Uitgeverij De Kring\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jeroenterlingen.nl\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/jeroenterlingen.nl\\\/site\\\/\",\"name\":\"Jeroen Terlingen\",\"description\":\"Schrijver, journalist, filmmaker, docent en begeleider manuscripten\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jeroenterlingen.nl\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Uitgeverij De Kring Archieven - Jeroen Terlingen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jeroenterlingen.nl\/site\/tag\/uitgeverij-de-kring\/","og_locale":"nl_NL","og_type":"article","og_title":"Uitgeverij De Kring Archieven - Jeroen Terlingen","og_url":"https:\/\/jeroenterlingen.nl\/site\/tag\/uitgeverij-de-kring\/","og_site_name":"Jeroen Terlingen","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/jeroenterlingen.nl\/site\/tag\/uitgeverij-de-kring\/","url":"https:\/\/jeroenterlingen.nl\/site\/tag\/uitgeverij-de-kring\/","name":"Uitgeverij De Kring Archieven - Jeroen Terlingen","isPartOf":{"@id":"https:\/\/jeroenterlingen.nl\/site\/#website"},"breadcrumb":{"@id":"https:\/\/jeroenterlingen.nl\/site\/tag\/uitgeverij-de-kring\/#breadcrumb"},"inLanguage":"nl-NL"},{"@type":"BreadcrumbList","@id":"https:\/\/jeroenterlingen.nl\/site\/tag\/uitgeverij-de-kring\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/jeroenterlingen.nl\/site\/"},{"@type":"ListItem","position":2,"name":"Uitgeverij De Kring"}]},{"@type":"WebSite","@id":"https:\/\/jeroenterlingen.nl\/site\/#website","url":"https:\/\/jeroenterlingen.nl\/site\/","name":"Jeroen Terlingen","description":"Schrijver, journalist, filmmaker, docent en begeleider manuscripten","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jeroenterlingen.nl\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"}]}},"_links":{"self":[{"href":"https:\/\/jeroenterlingen.nl\/site\/wp-json\/wp\/v2\/tags\/47","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jeroenterlingen.nl\/site\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/jeroenterlingen.nl\/site\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/jeroenterlingen.nl\/site\/wp-json\/wp\/v2\/posts?tags=47"},{"href":"https:\/\/jeroenterlingen.nl\/site\/wp-json\/wp\/v2\/pages?tags=47"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}